{"id":507,"date":"2024-04-23T14:09:11","date_gmt":"2024-04-23T14:09:11","guid":{"rendered":"https:\/\/beyup.es\/?post_type=proyectos&#038;p=507"},"modified":"2024-04-24T08:00:39","modified_gmt":"2024-04-24T08:00:39","slug":"impacto-de-la-campana-dooh-con-tecnologia-geoq","status":"publish","type":"proyectos","link":"https:\/\/beyup.es\/en\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/","title":{"rendered":"IMPACT OF THE DOOH CAMPAIGN WITH GEOQ TECHNOLOGY"},"content":{"rendered":"<p>Balizamos digitalmente los 3.500 mupis contratados. Empezamos a observar las personas que son impactadas con la campa\u00f1a de DOOH a trav\u00e9s de nuestra tecnolog\u00eda GEOQ. Diferenciamos los mupis y las dos creatividades. Con el objetivo de impactar a los usuarios que han visto la campa\u00f1a hasta 72 horas despu\u00e9s (3 d\u00edas).<\/p>\n\n\n\n<p>El 47% de los usuarios recibieron el impacto DOOH en un lugar de paso; el 41% se encontraba en la zona de influencia de su trabajo; y el 9% en la zona de influencia de su domicilio. La campa\u00f1a ha tenido una cobertura total del 48% de la poblaci\u00f3n que respond\u00eda al core target de la campa\u00f1a.<\/p>\n\n\n\n<p>La combinaci\u00f3n de DOOH y RT digital ha permitido un 17% m\u00e1s de visitas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Balizamos digitalmente los 3.500 mupis contratados. Empezamos a observar las personas que son impactadas con la campa\u00f1a de DOOH a trav\u00e9s de nuestra tecnolog\u00eda GEOQ. Diferenciamos los mupis y las dos creatividades. Con el objetivo de impactar a los usuarios que han visto la campa\u00f1a hasta 72 horas despu\u00e9s (3 d\u00edas). El 47% de los [&hellip;]<\/p>\n","protected":false},"featured_media":509,"template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_target":""},"categories":[],"tags":[48,49,42,43,45,47],"class_list":["post-507","proyectos","type-proyectos","status-publish","has-post-thumbnail","hentry","tag-tecnologia-geoq","tag-core-target","tag-etnografia","tag-geohabitos","tag-dooh","tag-geocomportamientos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ - Beyup<\/title>\n<meta name=\"description\" content=\"La campa\u00f1a ha tenido una cobertura total del 48% de la poblaci\u00f3n que respond\u00eda al core target de la campa\u00f1a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beyup.es\/en\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ - Beyup\" \/>\n<meta property=\"og:description\" content=\"La campa\u00f1a ha tenido una cobertura total del 48% de la poblaci\u00f3n que respond\u00eda al core target de la campa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beyup.es\/en\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/\" \/>\n<meta property=\"og:site_name\" content=\"Beyup\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T08:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beyup.es\/wp-content\/uploads\/sites\/6\/2024\/04\/pexels-negativespace-34639-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/\",\"url\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/\",\"name\":\"IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ - Beyup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beyup.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beyup.es\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/pexels-negativespace-34639-scaled.jpg\",\"datePublished\":\"2024-04-23T14:09:11+00:00\",\"dateModified\":\"2024-04-24T08:00:39+00:00\",\"description\":\"La campa\u00f1a ha tenido una cobertura total del 48% de la poblaci\u00f3n que respond\u00eda al core target de la campa\u00f1a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beyup.es\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/pexels-negativespace-34639-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/beyup.es\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/04\\\/pexels-negativespace-34639-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/impacto-de-la-campana-dooh-con-tecnologia-geoq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/beyup.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/beyup.es\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beyup.es\\\/#website\",\"url\":\"https:\\\/\\\/beyup.es\\\/\",\"name\":\"Beyup\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/beyup.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beyup.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/beyup.es\\\/#organization\",\"name\":\"Beyup\",\"url\":\"https:\\\/\\\/beyup.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/beyup.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/beyup.es\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Beyup_logo.svg\",\"contentUrl\":\"https:\\\/\\\/beyup.es\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2023\\\/05\\\/Beyup_logo.svg\",\"width\":855,\"height\":150,\"caption\":\"Beyup\"},\"image\":{\"@id\":\"https:\\\/\\\/beyup.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ - Beyup","description":"La campa\u00f1a ha tenido una cobertura total del 48% de la poblaci\u00f3n que respond\u00eda al core target de la campa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beyup.es\/en\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/","og_locale":"en_GB","og_type":"article","og_title":"IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ - Beyup","og_description":"La campa\u00f1a ha tenido una cobertura total del 48% de la poblaci\u00f3n que respond\u00eda al core target de la campa\u00f1a","og_url":"https:\/\/beyup.es\/en\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/","og_site_name":"Beyup","article_modified_time":"2024-04-24T08:00:39+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/beyup.es\/wp-content\/uploads\/sites\/6\/2024\/04\/pexels-negativespace-34639-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/","url":"https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/","name":"IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ - Beyup","isPartOf":{"@id":"https:\/\/beyup.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/#primaryimage"},"image":{"@id":"https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/#primaryimage"},"thumbnailUrl":"https:\/\/beyup.es\/wp-content\/uploads\/sites\/6\/2024\/04\/pexels-negativespace-34639-scaled.jpg","datePublished":"2024-04-23T14:09:11+00:00","dateModified":"2024-04-24T08:00:39+00:00","description":"La campa\u00f1a ha tenido una cobertura total del 48% de la poblaci\u00f3n que respond\u00eda al core target de la campa\u00f1a","breadcrumb":{"@id":"https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/#primaryimage","url":"https:\/\/beyup.es\/wp-content\/uploads\/sites\/6\/2024\/04\/pexels-negativespace-34639-scaled.jpg","contentUrl":"https:\/\/beyup.es\/wp-content\/uploads\/sites\/6\/2024\/04\/pexels-negativespace-34639-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/beyup.es\/proyectos\/impacto-de-la-campana-dooh-con-tecnologia-geoq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/beyup.es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/beyup.es\/proyectos\/"},{"@type":"ListItem","position":3,"name":"IMPACTO DE LA CAMPA\u00d1A DOOH CON TECNOLOG\u00cdA GEOQ"}]},{"@type":"WebSite","@id":"https:\/\/beyup.es\/#website","url":"https:\/\/beyup.es\/","name":"Beyonce","description":"","publisher":{"@id":"https:\/\/beyup.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beyup.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/beyup.es\/#organization","name":"Beyonce","url":"https:\/\/beyup.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/beyup.es\/#\/schema\/logo\/image\/","url":"https:\/\/beyup.es\/wp-content\/uploads\/sites\/6\/2023\/05\/Beyup_logo.svg","contentUrl":"https:\/\/beyup.es\/wp-content\/uploads\/sites\/6\/2023\/05\/Beyup_logo.svg","width":855,"height":150,"caption":"Beyup"},"image":{"@id":"https:\/\/beyup.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/beyup.es\/en\/wp-json\/wp\/v2\/proyectos\/507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beyup.es\/en\/wp-json\/wp\/v2\/proyectos"}],"about":[{"href":"https:\/\/beyup.es\/en\/wp-json\/wp\/v2\/types\/proyectos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beyup.es\/en\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/beyup.es\/en\/wp-json\/wp\/v2\/media?parent=507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beyup.es\/en\/wp-json\/wp\/v2\/categories?post=507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beyup.es\/en\/wp-json\/wp\/v2\/tags?post=507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}